{"id":4553,"date":"2025-01-28T19:35:31","date_gmt":"2025-01-28T18:35:31","guid":{"rendered":"https:\/\/cadence-epices-equitation.com\/?page_id=4553"},"modified":"2026-08-12T14:37:29","modified_gmt":"2026-08-12T12:37:29","slug":"randonnee-foret-deawy","status":"publish","type":"page","link":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/","title":{"rendered":"Randonn\u00e9e For\u00eat d&rsquo;Eawy 4 jours \/ 3 nuits"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4553\" class=\"elementor elementor-4553\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40d47f27 animated-slow elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"40d47f27\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbd6a68\" data-id=\"cbd6a68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a81aa80 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1a81aa80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Escapade priv\u00e9e en for\u00eat d'Eawy<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13270d21 elementor-widget elementor-widget-heading\" data-id=\"13270d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Voyage au coeur du pays de Bray et de ses traditions<br>4 jours - 3 nuits<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13896db2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13896db2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9a7f01\" data-id=\"b9a7f01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-400cb9d0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"400cb9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-455a7aa2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"455a7aa2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e99b931\" data-id=\"5e99b931\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3828b389 elementor-widget elementor-widget-menu-anchor\" data-id=\"3828b389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"haut\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11e2331f elementor-widget elementor-widget-heading\" data-id=\"11e2331f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Escapade priv\u00e9e en for\u00eat d'Eawy: Voyage au coeur du pays de Bray et de ses traditions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-def2db0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"def2db0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b76e4e\" data-id=\"8b76e4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b8780e elementor-widget elementor-widget-spacer\" data-id=\"4b8780e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-252c1ae5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"252c1ae5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45a24af\" data-id=\"45a24af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f34c50 elementor-widget elementor-widget-spacer\" data-id=\"7f34c50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e7266 elementor-widget elementor-widget-heading\" data-id=\"56e7266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Envie d'une aventure \u00e9questre authentique en petit groupe de 4 cavaliers maximum\u00a0?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53e9021 elementor-widget elementor-widget-text-editor\" data-id=\"53e9021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Partez \u00e0 la d\u00e9couverte des\u00a0<strong>sentiers f\u00e9eriques<\/strong>\u00a0de la for\u00eat d\u2019Eawy et des paysages typiques de la boutonni\u00e8re du pays de Bray.<\/p><p><span style=\"font-weight: 400;\">\u2728<\/span><span style=\"font-weight: 400;\"> Cette\u00a0<strong>randonn\u00e9e \u00e9questre dynamique<\/strong>\u00a0vous permettra de d\u00e9couvrir la nature, la\u00a0<strong>tradition<\/strong>\u00a0et la\u00a0<strong>culture Brayonne<\/strong>, dans une ambiance\u00a0<strong>chaleureuse<\/strong>\u00a0et conviviale. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6de7ee elementor-widget elementor-widget-heading\" data-id=\"e6de7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Une randonn\u00e9e \u00e0 cheval entre nature, villages normands et surprises<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e16f3f6 elementor-widget elementor-widget-text-editor\" data-id=\"e16f3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Explorez des\u00a0<strong>sentiers f\u00e9eriques<\/strong>\u00a0au c\u0153ur de l\u2019une des grandes h\u00eatraies fran\u00e7aises et d\u00e9couvrez les\u00a0<strong>paysages typiques de la boutonni\u00e8re du pays de Bray<\/strong>.<\/p><p style=\"font-weight: 400;\">Traversez des prairies verdoyantes, des for\u00eats myst\u00e9rieuses et des villages normands pittoresques.<\/p><p style=\"font-weight: 400;\">Chaque journ\u00e9e offre un itin\u00e9raire vari\u00e9, ponctu\u00e9 de moments inattendus et de surprises soigneusement pr\u00e9par\u00e9es, pour une exp\u00e9rience m\u00e9morable au rythme de votre cheval.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41469ef elementor-widget elementor-widget-heading\" data-id=\"41469ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Traditions locales et gourmandises normandes<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f92bf7 elementor-widget elementor-widget-text-editor\" data-id=\"5f92bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Cette escapade vous permettra de plonger dans l\u2019authenticit\u00e9 normande :<\/p><p style=\"font-weight: 400;\">\ud83c\udf4e\u00a0<strong>Saveurs du terroir<\/strong>\u00a0: d\u00e9gustez le cidre, les pommes et le c\u00e9l\u00e8bre c\u0153ur de Neufch\u00e2tel, l\u2019un des quatre fromages AOP de la r\u00e9gion.<\/p><p style=\"font-weight: 400;\">\ud83d\udc65\u00a0<strong>Rencontres avec les habitants<\/strong>\u00a0: vous rencontrerez des habitants qui prendront plaisir \u00e0 partager avec vous leur attachement \u00e0 leur r\u00e9gion et ses traditions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ce7a612\" data-id=\"ce7a612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe5bbee elementor-widget elementor-widget-spacer\" data-id=\"fe5bbee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7468395 elementor-widget elementor-widget-spacer\" data-id=\"7468395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a62556 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"0a62556\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-427c1ae swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"230a5e55-90a5-4aa4-b4ac-9e4e7bfca348\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9c22b3e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"photo foret\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1b4d29f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"randonn\u00e9e a cheval normandie\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d147a elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"b0d147a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-427c1ae swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Randonn\u00e9e foret Eawy paysage du pays de bray\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9c22b3e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Randonn\u00e9e foret Eawy paysage du pays de bray\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcb3628 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcb3628\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23e15c1\" data-id=\"23e15c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6da2014 elementor-widget elementor-widget-spacer\" data-id=\"6da2014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d348311 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d348311\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5dfb7ff\" data-id=\"5dfb7ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4e91a6 elementor-widget elementor-widget-spacer\" data-id=\"c4e91a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c95004b elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c95004b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-427c1ae swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"0e8d3a0e-4a59-4da7-ba79-b14e737f42ce\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-32868fb swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"randonn\u00e9e en for\u00eat d&#039;Eawy\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-887469b swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Enseignante equitation\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76b2385\" data-id=\"76b2385\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f3f635 elementor-widget elementor-widget-spacer\" data-id=\"9f3f635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbc9ef2 elementor-widget elementor-widget-heading\" data-id=\"cbc9ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Confort et convivialit\u00e9<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df484a2 elementor-widget elementor-widget-text-editor\" data-id=\"df484a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Apr\u00e8s une journ\u00e9e en pleine nature, reposez-vous dans un\u00a0<strong>g\u00eete confortable et accueillant<\/strong>.<\/p><p style=\"font-weight: 400;\">Profitez d\u2019une <strong>cuisine maison<\/strong>, alliant saveurs locales, \u00e9pices d\u00e9licates et inspirations du monde, pour terminer chaque journ\u00e9e dans une ambiance conviviale et gourmande.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a93d5a elementor-widget elementor-widget-heading\" data-id=\"5a93d5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Une guide passionn\u00e9e pour vous accompagner<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-725c579 elementor-widget elementor-widget-text-editor\" data-id=\"725c579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">En tant que guide passionn\u00e9e, je serai ravie de vous faire d\u00e9couvrir cette belle r\u00e9gion et de partager avec vous des moments uniques avec votre cheval, m\u00ealant complicit\u00e9 et authenticit\u00e9.<\/p><p style=\"font-weight: 400;\">Si vous \u00eates \u00e0 la recherche d\u2019une<strong> aventure authentique<\/strong>, m\u00ealant nature, culture et convivialit\u00e9, cette escapade en for\u00eat d\u2019Eawy est faite pour vous.<\/p><p style=\"font-weight: 400;\"><strong>Rejoignez-nous<\/strong> pour une exp\u00e9rience hors du temps et laissez-vous guider par une enseignante passionn\u00e9e dans la d\u00e9couverte du pays de Bray.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ac312a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ac312a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3846fae\" data-id=\"3846fae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-377fcd9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"377fcd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78e40cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78e40cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-418f5d9\" data-id=\"418f5d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad1965b elementor-widget elementor-widget-heading\" data-id=\"ad1965b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Si vous r\u00eavez d\u2019une aventure m\u00ealant nature, traditions et convivialit\u00e9, cette escapade en for\u00eat d\u2019Eawy est faite pour vous ! <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be0e03c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be0e03c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0799d57\" data-id=\"0799d57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa1dd96 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fa1dd96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba2acfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba2acfe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0869708\" data-id=\"0869708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef05728 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"ef05728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#haut\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37e7c14 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"37e7c14\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05b5997\" data-id=\"05b5997\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8471758 elementor-widget elementor-widget-heading\" data-id=\"8471758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programme d\u00e9taill\u00e9 - Dates &amp;  Tarifs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c841ff9 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c841ff9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61cb8a3\" data-id=\"61cb8a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ee2ae7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ee2ae7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-87f4198\" data-id=\"87f4198\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3f2338 elementor-widget elementor-widget-heading\" data-id=\"d3f2338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programme d\u00e9taill\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0288bfe elementor-widget elementor-widget-toggle\" data-id=\"0288bfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Journ\u00e9e 1<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2651\"><p>D\u00e9part des \u00e9curies pour rejoindre les sentiers de la for\u00eat d\u2019Eawy.<br \/>Nous passerons par le puits merveilleux, gouffre enchanteur objet de nombreuses histoires et l\u00e9gendes locales. Nous emprunterons \u00e9galement par moment l\u2019all\u00e9e des limousins, all\u00e9e remarquable en for\u00eat d\u2019Eawy presque parfaitement rectiligne.<br \/>Diner et nuit dans un g\u00eete confortable en bordure de for\u00eat .<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2652\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2652\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Journ\u00e9e 2<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2652\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2652\"><p>Nous quittons les sentiers f\u00e9eriques de la for\u00eat pour d\u00e9couvrir les paysages de la boutonni\u00e8re. Nous arrivons en fin de journ\u00e9e dans une ferme du 16\u00e8me si\u00e8cle d\u2019un ancien monast\u00e8re o\u00f9 nous s\u00e9journerons pour deux nuits, dans l\u2019ancienne \u00e9curie de la ferme enti\u00e8rement r\u00e9nov\u00e9e en g\u00eete ind\u00e9pendant.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2653\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2653\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Journ\u00e9e 3<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2653\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2653\"><p>Nous partons ce matin pour une belle boucle dans le paysage vallonn\u00e9 Brayons o\u00f9 nous pourrons profiter de beaux panoramas sur la boutonni\u00e8re et sur la for\u00eat d\u2019Eawy.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2654\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2654\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Journ\u00e9e 4<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2654\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2654\"><p>Retour aux \u00e9curies \u00e0 travers la for\u00eat d\u2019Eawy sur des sentiers tant\u00f4t en lisi\u00e8re, tant\u00f4t en pleine for\u00eat.<br \/>Suivant le parcours, nous traverserons Saint-Sa\u00ebns, village typique du pays de Bray o\u00f9 vous pourrez d\u00e9couvrir ses maisons \u00e0 colombages et son \u00e9glise du19\u00e8me si\u00e8cle.<br \/>Nous aurons peut-\u00eatre la chance en parcourant les sentiers de croiser au d\u00e9tour d\u2019un chemin un cerf, animal embl\u00e9matique de cette belle for\u00eat.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10b121a elementor-widget elementor-widget-text-editor\" data-id=\"10b121a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NB : le programme de la randonn\u00e9e est fourni \u00e0 titre indicatif et peut \u00e9voluer en fonctions des al\u00e9as m\u00e9t\u00e9os et autres.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72112f6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72112f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce2cf29\" data-id=\"ce2cf29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9016649 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9016649\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9472751\" data-id=\"9472751\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ae84eb elementor-widget elementor-widget-heading\" data-id=\"5ae84eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dates 2027<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-809e806 elementor-widget elementor-widget-text-editor\" data-id=\"809e806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"emoji lazyload\" role=\"img\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f4c5.svg\" alt=\"\ud83d\udcc5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/> Prochains d\u00e9parts :<br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0&#8211; 24 au 27 juin 2027<br \/>D\u00e9part garanti \u00e0 partir de 2.<br \/>Dates suppl\u00e9mentaires sur demande possible.<\/p><p><img decoding=\"async\" class=\"emoji lazyload\" role=\"img\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/23f3.svg\" alt=\"\u23f3\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\u00a0<strong>Dur\u00e9e<\/strong>\u00a0: 4 jours \/ 3 nuits<\/p><p style=\"font-weight: 400;\"><img decoding=\"async\" class=\"emoji lazyload\" role=\"img\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f512.svg\" alt=\"\ud83d\udd12\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/> <strong>R\u00e9servations limit\u00e9es<\/strong>\u00a0<strong>\u00e0 4 places<\/strong>: 2 avec les chevaux de l\u2019\u00e9curie<br \/>Les places sont limit\u00e9es pour garantir une exp\u00e9rience intime et personnalis\u00e9.<\/p><p style=\"font-weight: 400;\">Possibilit\u00e9 de valider les journ\u00e9es de randonn\u00e9e sur le carnet FFE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6a43b0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6a43b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f21331\" data-id=\"9f21331\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fed5887 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fed5887\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ecd4820\" data-id=\"ecd4820\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430ec2b elementor-widget elementor-widget-heading\" data-id=\"430ec2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tarifs 2027<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da3383e elementor-widget elementor-widget-text-editor\" data-id=\"da3383e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>895 \u20ac TTC avec les chevaux de l&rsquo;\u00e9curie<br \/>755\u20ac TTC pour les cavaliers propri\u00e9taires<br \/>Acompte de 30% demand\u00e9 \u00e0 la reservation &amp; le solde 30 jours avant le d\u00e9part.<br \/>Voir conditions g\u00e9n\u00e9rales de vente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-80e5217 elementor-widget elementor-widget-toggle\" data-id=\"80e5217\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le prix comprend<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1351\"><p style=\"font-weight: 400; padding-left: 40px;\">\u00a0&#8211; l&rsquo;h\u00e9bergement en g\u00eete les soirs de randonn\u00e9e (hors veille et jour final de la randonn\u00e9e)<br \/>\u00a0&#8211; les repas tel que d\u00e9cris dans le descriptif durant la randonn\u00e9e (hors diner du dernier jour)<br \/>\u00a0&#8211; l&rsquo;h\u00e9bergement en pr\u00e9 des chevaux dans les haltes, inclus foin mais pas de grain<br \/>\u00a0&#8211; les prestations de guide ainsi que la logistique\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1352\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1352\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le prix ne comprend pas:<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1352\"><p>\u00a0&#8211; tout ce qui n&rsquo;est pas inclus dans \u00ab\u00a0le prix comprend\u00a0\u00bb et notamment<br \/>\u00a0&#8211; transport des chevaux de propri\u00e9taires et rapatriement en cours de randonn\u00e9e en cas d&rsquo;impr\u00e9vu<br \/>\u00a0&#8211; Assurances personnelles + assurances de responsabilit\u00e9 civile propri\u00e9taire d&rsquo;\u00e9quid\u00e9 pour les chevaux des propri\u00e9taires<br \/>\u00a0&#8211; D\u00e9penses personnelles, boissons au cours de la randonn\u00e9e<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a402ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a402ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9a6bdd\" data-id=\"b9a6bdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f240df0 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"f240df0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#haut\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Escapade priv\u00e9e en for\u00eat d&rsquo;Eawy Voyage au coeur du pays de Bray et de ses traditions4 jours &#8211; 3 nuits Escapade priv\u00e9e en for\u00eat d&rsquo;Eawy: Voyage au coeur du pays de Bray et de ses traditions Envie d&rsquo;une aventure \u00e9questre authentique en petit groupe de 4 cavaliers maximum\u00a0? Partez \u00e0 la d\u00e9couverte des\u00a0sentiers f\u00e9eriques\u00a0de la&hellip;&nbsp;<a href=\"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/\" class=\"\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Randonn\u00e9e For\u00eat d&rsquo;Eawy 4 jours \/ 3 nuits<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-4553","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Escapade priv\u00e9e en For\u00eat d&#039;Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d&#039;une aventure \u00e9questre authentique \u00e0 2h de l&#039;Ile de France en petit\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecurie Cadence et Epices | Demander souvent, se contenter de peu, r\u00e9compenser beaucoup\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices\" \/>\n\t\t<meta property=\"og:description\" content=\"Escapade priv\u00e9e en For\u00eat d&#039;Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d&#039;une aventure \u00e9questre authentique \u00e0 2h de l&#039;Ile de France en petit\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-28T18:35:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-12T12:37:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Escapade priv\u00e9e en For\u00eat d&#039;Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d&#039;une aventure \u00e9questre authentique \u00e0 2h de l&#039;Ile de France en petit\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cadence-epices-equitation.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#listItem\",\"name\":\"Randonn\\u00e9e For\\u00eat d&rsquo;Eawy 4 jours \\\/ 3 nuits\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#listItem\",\"position\":2,\"name\":\"Randonn\\u00e9e For\\u00eat d&rsquo;Eawy 4 jours \\\/ 3 nuits\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/#organization\",\"name\":\"Cadence & Epices - Monitrice et Cavali\\u00e8re ind\\u00e9pendante\",\"description\":\"Demander souvent, se contenter de peu, r\\u00e9compenser beaucoup\",\"url\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CadenceEpices-Modifie.png\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#organizationLogo\",\"width\":743,\"height\":746},\"image\":{\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#webpage\",\"url\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/\",\"name\":\"Randonn\\u00e9e For\\u00eat d\\u2019Eawy 4 jours \\\/ 3 nuits | Ecurie Cadence et Epices\",\"description\":\"Escapade priv\\u00e9e en For\\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \\u00e9questre authentique \\u00e0 2h de l'Ile de France en petit\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/index.php\\\/randonnee-foret-deawy\\\/#breadcrumblist\"},\"datePublished\":\"2025-01-28T19:35:31+01:00\",\"dateModified\":\"2026-08-12T14:37:29+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/#website\",\"url\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/\",\"name\":\"Ecurie Cadence et Epices\",\"description\":\"Demander souvent, se contenter de peu, r\\u00e9compenser beaucoup\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/cadence-epices-equitation.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices","description":"Escapade priv\u00e9e en For\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \u00e9questre authentique \u00e0 2h de l'Ile de France en petit","canonical_url":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/cadence-epices-equitation.com#listItem","position":1,"name":"Accueil","item":"https:\/\/cadence-epices-equitation.com","nextItem":{"@type":"ListItem","@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#listItem","name":"Randonn\u00e9e For\u00eat d&rsquo;Eawy 4 jours \/ 3 nuits"}},{"@type":"ListItem","@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#listItem","position":2,"name":"Randonn\u00e9e For\u00eat d&rsquo;Eawy 4 jours \/ 3 nuits","previousItem":{"@type":"ListItem","@id":"https:\/\/cadence-epices-equitation.com#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/cadence-epices-equitation.com\/#organization","name":"Cadence & Epices - Monitrice et Cavali\u00e8re ind\u00e9pendante","description":"Demander souvent, se contenter de peu, r\u00e9compenser beaucoup","url":"https:\/\/cadence-epices-equitation.com\/","logo":{"@type":"ImageObject","url":"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png","@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#organizationLogo","width":743,"height":746},"image":{"@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#webpage","url":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/","name":"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices","description":"Escapade priv\u00e9e en For\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \u00e9questre authentique \u00e0 2h de l'Ile de France en petit","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/cadence-epices-equitation.com\/#website"},"breadcrumb":{"@id":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/#breadcrumblist"},"datePublished":"2025-01-28T19:35:31+01:00","dateModified":"2026-08-12T14:37:29+02:00"},{"@type":"WebSite","@id":"https:\/\/cadence-epices-equitation.com\/#website","url":"https:\/\/cadence-epices-equitation.com\/","name":"Ecurie Cadence et Epices","description":"Demander souvent, se contenter de peu, r\u00e9compenser beaucoup","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/cadence-epices-equitation.com\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Ecurie Cadence et Epices | Demander souvent, se contenter de peu, r\u00e9compenser beaucoup","og:type":"article","og:title":"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices","og:description":"Escapade priv\u00e9e en For\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \u00e9questre authentique \u00e0 2h de l'Ile de France en petit","og:url":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/","og:image":"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png","og:image:secure_url":"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png","article:published_time":"2025-01-28T18:35:31+00:00","article:modified_time":"2026-08-12T12:37:29+00:00","twitter:card":"summary","twitter:title":"Randonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits | Ecurie Cadence et Epices","twitter:description":"Escapade priv\u00e9e en For\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \u00e9questre authentique \u00e0 2h de l'Ile de France en petit","twitter:image":"https:\/\/cadence-epices-equitation.com\/wp-content\/uploads\/2022\/02\/CadenceEpices-Modifie.png"},"aioseo_meta_data":{"post_id":"4553","title":"#post_title #separator_sa #site_title","description":"Escapade priv\u00e9e en For\u00eat d'Eawy: voyage au coeur du pays de Bray et de ses traditions. Envie d'une aventure \u00e9questre authentique \u00e0 2h de l'Ile de France en petit","keywords":null,"keyphrases":{"focus":{"keyphrase":"randonn\u00e9e \u00e0 cheval","score":37,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-28 18:38:40","updated":"2026-08-13 13:30:02","seo_analyzer_scan_date":null,"focus_keyword":"randonn\u00e9e \u00e0 cheval","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cadence-epices-equitation.com\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRandonn\u00e9e For\u00eat d\u2019Eawy 4 jours \/ 3 nuits\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/cadence-epices-equitation.com"},{"label":"Randonn\u00e9e For\u00eat d&rsquo;Eawy 4 jours \/ 3 nuits","link":"https:\/\/cadence-epices-equitation.com\/index.php\/randonnee-foret-deawy\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/pages\/4553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/comments?post=4553"}],"version-history":[{"count":171,"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/pages\/4553\/revisions"}],"predecessor-version":[{"id":5360,"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/pages\/4553\/revisions\/5360"}],"wp:attachment":[{"href":"https:\/\/cadence-epices-equitation.com\/index.php\/wp-json\/wp\/v2\/media?parent=4553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}